{"id":12618,"date":"2025-02-21T10:35:01","date_gmt":"2025-02-21T13:35:01","guid":{"rendered":"https:\/\/horapicodigital.com.ar\/?p=12618"},"modified":"2025-02-21T10:39:16","modified_gmt":"2025-02-21T13:39:16","slug":"la-salud-del-papa-paso-una-buena-noche-y-logro-levantarse","status":"publish","type":"post","link":"https:\/\/horapicodigital.com.ar\/index.php\/2025\/02\/21\/la-salud-del-papa-paso-una-buena-noche-y-logro-levantarse\/","title":{"rendered":"La salud del Papa: pas\u00f3 una buena noche y logr\u00f3 levantarse"},"content":{"rendered":"\n<h2 class=\"wp-block-heading\">El Vaticano difundi\u00f3 un nuevo reporte m\u00e9dico del Sumo Pont\u00edfice que ya lleva una semana internado en el policl\u00ednico Gemelli&nbsp;de Roma por una infecci\u00f3n polimicrobiana. \u00abLa noche ha transcurrido bien\u00bb, se\u00f1alaron.<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>El&nbsp;papa Francisco&nbsp;muestra desde hace unos d\u00edas una&nbsp;\u00ableve mejor\u00eda\u00bb&nbsp;en su estado de salud.&nbsp;<\/strong>As\u00ed lo hab\u00eda confirmado la oficina del prensa del Vaticano en su parte m\u00e9dico del jueves y lo ratific\u00f3 en el de este viernes. El Santo Padre cumple una semana internado en el policl\u00ednico Gemelli de Roma producto de una infecci\u00f3n polimicrobiana.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">En los \u00faltimos d\u00edas Francisco dej\u00f3 de tener&nbsp;fiebre&nbsp;y sus par\u00e1metros hemodin\u00e1micos&nbsp;se mantienen estables. Producto de esta mejor\u00eda, ya&nbsp;<strong>desde el jueves fue retomando sus actividades de trabajo<\/strong>, siempre con los cuidados pertinentes.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Este viernes incluso logr\u00f3 salir de la cama de internaci\u00f3n y se sent\u00f3 a desayunar.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Francisco, de 87 a\u00f1os,&nbsp;<strong>fue ingresado hace una semana en el&nbsp;hospital Gemelli de Roma<\/strong>&nbsp;tras ser diagnosticado con una&nbsp;neumon\u00eda bilateral. Aunque su evoluci\u00f3n es favorable, los m\u00e9dicos contin\u00faan con un seguimiento cercano de su estado de salud.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Seg\u00fan la informaci\u00f3n oficial, Francisco continuaba con su actividad laboral y&nbsp;el \u00faltimo mi\u00e9rcoles<strong>&nbsp;hab\u00eda recibido la visita de la Primera ministra&nbsp;italiana, Giorgia Meloni<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Desde Italia, en di\u00e1logo con Radi\u00f3polis (Radio 2),&nbsp;el periodista Guido Gazzoli, abon\u00f3 tal informaci\u00f3n, aunque, consultado sobre si existe la posibilidad de que la versi\u00f3n del Vaticano \u201coculte\u201d la realidad sobre la evoluci\u00f3n de Bergoglio, el entrevistado no neg\u00f3 tal chance.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El Vaticano ya hab\u00eda informado el lunes que el&nbsp;Papa, ingresado desde el viernes,&nbsp;<strong>padec\u00eda una \u00abinfecci\u00f3n polimicrobiana de las v\u00edas respiratorias\u00bb<\/strong>&nbsp;y&nbsp;<strong>presentaba un&nbsp;\u00abcuadro cl\u00ednico complejo\u00bb,<\/strong>&nbsp;lo que indicaba que&nbsp;permanecer\u00eda hospitalizado al menos hasta el mi\u00e9rcoles, fecha en la que deb\u00eda encabezar su audiencia general, ya cancelada.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>El Vaticano difundi\u00f3 un nuevo reporte m\u00e9dico del Sumo Pont\u00edfice que ya lleva una semana internado en el policl\u00ednico Gemelli&nbsp;de Roma por una infecci\u00f3n polimicrobiana. \u00abLa noche ha transcurrido bien\u00bb, se\u00f1alaron. El&nbsp;papa Francisco&nbsp;muestra desde hace unos d\u00edas una&nbsp;\u00ableve mejor\u00eda\u00bb&nbsp;en su estado de salud.&nbsp;As\u00ed lo hab\u00eda confirmado la oficina del prensa del Vaticano en su parte [&hellip;]<\/p>\n","protected":false},"author":7,"featured_media":12619,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_themeisle_gutenberg_block_has_review":false,"footnotes":""},"categories":[7],"tags":[19,348],"class_list":["post-12618","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-mundo","tag-mundo","tag-papa-francisco"],"_links":{"self":[{"href":"https:\/\/horapicodigital.com.ar\/index.php\/wp-json\/wp\/v2\/posts\/12618","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/horapicodigital.com.ar\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/horapicodigital.com.ar\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/horapicodigital.com.ar\/index.php\/wp-json\/wp\/v2\/users\/7"}],"replies":[{"embeddable":true,"href":"https:\/\/horapicodigital.com.ar\/index.php\/wp-json\/wp\/v2\/comments?post=12618"}],"version-history":[{"count":2,"href":"https:\/\/horapicodigital.com.ar\/index.php\/wp-json\/wp\/v2\/posts\/12618\/revisions"}],"predecessor-version":[{"id":12622,"href":"https:\/\/horapicodigital.com.ar\/index.php\/wp-json\/wp\/v2\/posts\/12618\/revisions\/12622"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/horapicodigital.com.ar\/index.php\/wp-json\/wp\/v2\/media\/12619"}],"wp:attachment":[{"href":"https:\/\/horapicodigital.com.ar\/index.php\/wp-json\/wp\/v2\/media?parent=12618"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/horapicodigital.com.ar\/index.php\/wp-json\/wp\/v2\/categories?post=12618"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/horapicodigital.com.ar\/index.php\/wp-json\/wp\/v2\/tags?post=12618"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}